{"id":78,"date":"2015-09-05T06:30:38","date_gmt":"2015-09-05T01:00:38","guid":{"rendered":"http:\/\/keaweather.net\/?p=28"},"modified":"2015-09-05T06:30:38","modified_gmt":"2015-09-05T01:00:38","slug":"weather-4-newbies","status":"publish","type":"post","link":"https:\/\/kwschennai.com\/blog\/weather-4-newbies\/","title":{"rendered":"Weather 4 newbies"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","footnotes":""},"categories":[7],"tags":[],"class_list":["post-78","post","type-post","status-publish","format-standard","hentry","category-pages"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/posts\/78"}],"collection":[{"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/comments?post=78"}],"version-history":[{"count":0,"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/posts\/78\/revisions"}],"wp:attachment":[{"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/media?parent=78"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/categories?post=78"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/kwschennai.com\/blog\/wp-json\/wp\/v2\/tags?post=78"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}